{"id":16787,"date":"2021-02-01T21:03:33","date_gmt":"2021-02-02T00:03:33","guid":{"rendered":"https:\/\/guiadenoticias.com.ar\/diario\/?p=16787"},"modified":"2021-02-01T21:09:36","modified_gmt":"2021-02-02T00:09:36","slug":"ghi-entrego-subsidios-del-programa-clubes-en-obras","status":"publish","type":"post","link":"https:\/\/guiadenoticias.com.ar\/diario\/ghi-entrego-subsidios-del-programa-clubes-en-obras\/","title":{"rendered":"Ghi entreg\u00f3 subsidios del programa Clubes en Obras"},"content":{"rendered":"<p>El intendente de Mor\u00f3n, <strong>Lucas Ghi<\/strong>, visit\u00f3 el Club Sociedad Italiana de Tiro al Blanco (SITAS) de El Palomar y el Club Mor\u00f3n para hacer entrega del subsidio correspondiente al <strong>programa Clubes en Obras<\/strong> del <strong>Ministerio de Turismo y Deportes de la Naci\u00f3n<\/strong>, destinado a mejoras de infraestructura.<\/p>\n<p>Este aporte econ\u00f3mico tiene como objetivo apoyar la adquisici\u00f3n de materiales y garantizar la realizaci\u00f3n de proyectos de refacci\u00f3n, ampliaci\u00f3n y mantenimiento de instalaciones.<\/p>\n<p>Al finalizar la jornada, el jefe comunal resalt\u00f3: \u201cEl deporte y la actividad f\u00edsica constituyen uno de los derechos centrales tambi\u00e9n a garantizar por parte del Estado, lo que buscamos es fortalecer todo el entramado de instituciones comunitarias y sociales. Adem\u00e1s, fortalecemos la capacidad de educar, formar, de crecer con afecto y en entornos cuidados. Gracias a este aporte que realizamos de manera conjunta entre Naci\u00f3n y el municipio, sabemos que van a capitalizarlo en pos de los beneficios de sus socios y socias\u201d.<\/p>\n<p>En cuanto a las reformas edilicias, el presidente del SITAS, Daniel Zazaglia, detall\u00f3: \u201cEste subsidio se va a usar para hacer un nuevo espacio para gimnasia. Ac\u00e1 hay contenci\u00f3n, los chicos aprenden los valores, el respeto, hacen amigos y nosotros, con toda la ayuda que nos da el municipio, hacemos obras\u201d.<\/p>\n<p>Por su parte, el coordinador del Club Mor\u00f3n, Jorge Plez, detall\u00f3 que el subsidio les permitir\u00e1 realizar reformas y mejoras en uno de los techos correspondientes a la cancha de b\u00e1squet.<\/p>\n<p>Adem\u00e1s de este beneficio, ambas instituciones reciben el Fondo de Fortalecimiento Institucional comunal que tiene como fin realizar mejoras, reformas, reparaciones o acondicionamiento, entre otras acciones, en instituciones y asociaciones civiles sin fines de lucro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El intendente de Mor\u00f3n, Lucas Ghi, visit\u00f3 el Club Sociedad Italiana de Tiro al Blanco (SITAS) de El Palomar y el Club Mor\u00f3n para hacer entrega del subsidio correspondiente al programa Clubes en Obras del Ministerio de Turismo y Deportes de la Naci\u00f3n, destinado a mejoras de infraestructura. Este aporte econ\u00f3mico tiene como objetivo apoyar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16788,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,20],"tags":[73],"class_list":["post-16787","post","type-post","status-publish","format-standard","has-post-thumbnail","category-moron","category-municipios","tag-lucas-ghi"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Gu\u00eda de Noticias\"\/>\n\t<meta name=\"keywords\" content=\"lucas ghi,mor\u00f3n,municipios\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/guiadenoticias.com.ar\/diario\/ghi-entrego-subsidios-del-programa-clubes-en-obras\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Gu\u00eda de Noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ghi entreg\u00f3 subsidios del programa Clubes en Obras |\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/guiadenoticias.com.ar\/diario\/ghi-entrego-subsidios-del-programa-clubes-en-obras\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2021\/02\/clubes.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2021\/02\/clubes.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"497\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-02-02T00:03:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-02-02T00:09:36+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Guia-de-Noticias-1075696352450389\" \/>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ghi entreg\u00f3 subsidios del programa Clubes en Obras |","description":"","canonical_url":"https:\/\/guiadenoticias.com.ar\/diario\/ghi-entrego-subsidios-del-programa-clubes-en-obras\/","robots":"max-image-preview:large","keywords":"lucas ghi,mor\u00f3n,municipios","webmasterTools":{"miscellaneous":""},"schema":null,"og:locale":"es_ES","og:site_name":"Gu\u00eda de Noticias","og:type":"article","og:title":"Ghi entreg\u00f3 subsidios del programa Clubes en Obras |","og:url":"https:\/\/guiadenoticias.com.ar\/diario\/ghi-entrego-subsidios-del-programa-clubes-en-obras\/","og:image":"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2021\/02\/clubes.jpg","og:image:secure_url":"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2021\/02\/clubes.jpg","og:image:width":800,"og:image:height":497,"article:published_time":"2021-02-02T00:03:33+00:00","article:modified_time":"2021-02-02T00:09:36+00:00","article:publisher":"https:\/\/www.facebook.com\/Guia-de-Noticias-1075696352450389"},"aioseo_meta_data":{"post_id":"16787","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"none","schema_type_options":"{\"webPage\":{\"webPageType\":\"WebPage\"},\"article\":{\"articleType\":\"BlogPosting\"},\"book\":[],\"course\":[],\"event\":[],\"jobPosting\":[],\"music\":[],\"person\":[],\"product\":[],\"recipe\":[],\"restaurant\":[],\"service\":[],\"software\":[],\"video\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"businessInfo":{"name":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"line1":"","line2":"","zip":"","city":"","state":"","country":""},"contact":{"email":"","phone":"","fax":""},"ids":{"vatID":"","taxID":"","chamberID":""},"payment":{"priceIndication":"","currenciesAccepted":"","methodsAccepted":""},"areaServed":""},"openingHours":{"show":false,"closedLabel":"","open24h":false,"open24hLabel":"","open247":false,"use24hFormat":false,"twoSets":false,"timezone":"","hours":[]}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-02-01 23:59:45","updated":"2025-06-05 05:44:15","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts\/16787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/comments?post=16787"}],"version-history":[{"count":3,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts\/16787\/revisions"}],"predecessor-version":[{"id":16791,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts\/16787\/revisions\/16791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/media\/16788"}],"wp:attachment":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/media?parent=16787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/categories?post=16787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/tags?post=16787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}