{"id":17258,"date":"2021-04-18T23:04:17","date_gmt":"2021-04-19T02:04:17","guid":{"rendered":"https:\/\/guiadenoticias.com.ar\/diario\/?p=17258"},"modified":"2021-04-26T01:37:32","modified_gmt":"2021-04-26T04:37:32","slug":"desplazaron-a-18-policias-por-una-fiesta-clandestina","status":"publish","type":"post","link":"https:\/\/guiadenoticias.com.ar\/diario\/desplazaron-a-18-policias-por-una-fiesta-clandestina\/","title":{"rendered":"Desplazaron a 18 polic\u00edas por una fiesta clandestina"},"content":{"rendered":"<p>En el marco de las restricciones decretadas por el presidente Alberto Fern\u00e1ndez, un grupo de oficiales de la polic\u00eda bonaerense fue desplazado por haber organizado una supuesta fiesta clandestina en la <strong>Comisar\u00eda N\u00b06 de Ciudadela Norte<\/strong>, en el barrio Ej\u00e9rcito de los Andes. La informaci\u00f3n fue confirmada por fuentes del <strong>Ministerio de Seguridad de Buenos Aires.<\/strong><\/p>\n<p>Primero trascendi\u00f3 la decisi\u00f3n de apartar al jefe de la dependencia, Juan Ernesto Gloss, quien fue corrido del cargo luego de que trascendieron las im\u00e1genes en redes sociales.<\/p>\n<p>En un breve comunicado, desde el Ministerio de Seguridad bonaerense indicaron que la decisi\u00f3n se produjo tras la difusi\u00f3n en las redes sociales y en los medios de im\u00e1genes que habr\u00edan capturado momentos de la supuesta fiesta llevada a cabo el fin de semana, en la Comisar\u00eda N\u00b06 de Ciudadela Norte, que depende de la Superintendencia AMBA Norte II.<\/p>\n<p>Seg\u00fan el informe oficial, ante esta situaci\u00f3n se notific\u00f3 al Juzgado Federal, Criminal y Correccional 2 y la Secretar\u00eda 5 de San Mart\u00edn para que se inicie la investigaci\u00f3n penal preparatoria correspondiente y averiguaci\u00f3n de il\u00edcito. A su vez, desde la Direcci\u00f3n General de Asuntos Internos se dispuso \u201cla desafecci\u00f3n inmediata\u201d de los efectivos involucrados en el hecho.<\/p>\n<p>\u201cEs injusto manchar la excelente labor que se viene realizando con directivas claras por parte del ministro Sergio Berni por el accionar de 18 efectivos, por eso sin lugar a dudas se tom\u00f3 una r\u00e1pida intervenci\u00f3n\u201d, se se\u00f1al\u00f3 desde la cartera provincial.<\/p>\n<p>En las im\u00e1genes viralizadas se observa a los efectivos vestidos con su uniforme tomando bebidas alcoh\u00f3licas y escuchando m\u00fasica a alto volumen junto a un patrullero. En otra de las fotos, un grupo de 19 personas est\u00e1 con vestimentas de civil y con el uniforme de la polic\u00eda, en un ambiente cerrado y sin la utilizaci\u00f3n de barbijos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de las restricciones decretadas por el presidente Alberto Fern\u00e1ndez, un grupo de oficiales de la polic\u00eda bonaerense fue desplazado por haber organizado una supuesta fiesta clandestina en la Comisar\u00eda N\u00b06 de Ciudadela Norte, en el barrio Ej\u00e9rcito de los Andes. La informaci\u00f3n fue confirmada por fuentes del Ministerio de Seguridad de Buenos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17259,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,70,20],"tags":[81,89],"class_list":["post-17258","post","type-post","status-publish","format-standard","has-post-thumbnail","category-informacion-general","category-las-mas-leidas","category-municipios","tag-coronavirus","tag-inseguridad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Gu\u00eda de Noticias\"\/>\n\t<meta name=\"keywords\" content=\"coronavirus,inseguridad,informaci\u00f3n general,las m\u00e1s leidas,municipios\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/guiadenoticias.com.ar\/diario\/desplazaron-a-18-policias-por-una-fiesta-clandestina\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Gu\u00eda de Noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Desplazaron a 18 polic\u00edas por una fiesta clandestina |\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/guiadenoticias.com.ar\/diario\/desplazaron-a-18-policias-por-una-fiesta-clandestina\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2021\/04\/polis.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2021\/04\/polis.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-04-19T02:04:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-04-26T04:37:32+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Guia-de-Noticias-1075696352450389\" \/>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Desplazaron a 18 polic\u00edas por una fiesta clandestina |","description":"","canonical_url":"https:\/\/guiadenoticias.com.ar\/diario\/desplazaron-a-18-policias-por-una-fiesta-clandestina\/","robots":"max-image-preview:large","keywords":"coronavirus,inseguridad,informaci\u00f3n general,las m\u00e1s leidas,municipios","webmasterTools":{"miscellaneous":""},"schema":null,"og:locale":"es_ES","og:site_name":"Gu\u00eda de Noticias","og:type":"article","og:title":"Desplazaron a 18 polic\u00edas por una fiesta clandestina |","og:url":"https:\/\/guiadenoticias.com.ar\/diario\/desplazaron-a-18-policias-por-una-fiesta-clandestina\/","og:image":"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2021\/04\/polis.jpg","og:image:secure_url":"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2021\/04\/polis.jpg","og:image:width":700,"og:image:height":394,"article:published_time":"2021-04-19T02:04:17+00:00","article:modified_time":"2021-04-26T04:37:32+00:00","article:publisher":"https:\/\/www.facebook.com\/Guia-de-Noticias-1075696352450389"},"aioseo_meta_data":{"post_id":"17258","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"phone":"","email":"","fax":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-04-19 01:59:50","updated":"2025-06-05 05:58:51","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts\/17258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/comments?post=17258"}],"version-history":[{"count":1,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts\/17258\/revisions"}],"predecessor-version":[{"id":17260,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts\/17258\/revisions\/17260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/media\/17259"}],"wp:attachment":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/media?parent=17258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/categories?post=17258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/tags?post=17258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}