{"id":17861,"date":"2021-06-28T01:44:53","date_gmt":"2021-06-28T04:44:53","guid":{"rendered":"https:\/\/guiadenoticias.com.ar\/diario\/?p=17861"},"modified":"2021-06-29T01:45:20","modified_gmt":"2021-06-29T04:45:20","slug":"avanzan-las-refacciones-en-escuelas-de-moron","status":"publish","type":"post","link":"https:\/\/guiadenoticias.com.ar\/diario\/avanzan-las-refacciones-en-escuelas-de-moron\/","title":{"rendered":"Avanzan las refacciones en escuelas de Mor\u00f3n"},"content":{"rendered":"<p><strong>El intendente Lucas Ghi recorri\u00f3 la Escuela Primaria N\u00ba11 de Villa Sarmiento para supervisar las obras de refacci\u00f3n que se llevan adelante a trav\u00e9s del programa bonaerense Escuelas a la Obra.<\/strong><\/p>\n<p>Las intervenciones constan de la renovaci\u00f3n completa de los ba\u00f1os con trabajos de ventilaci\u00f3n e iluminaci\u00f3n incluidas. Cuentan con una inversi\u00f3n de 2.239.000 de pesos y se desarrollan entre Provincia y el Consejo Escolar.<\/p>\n<p>En ese sentido, el jefe comunal detall\u00f3 que \u201crenovamos todo el equipamiento de los ba\u00f1os, reconstruidos \u00edntegramente, en el retorno a esta presencialidad para que sea en condiciones de seguridad, higiene y confort\u201d. Y agreg\u00f3: \u00abEs una inversi\u00f3n significativa que va a permitir que los ni\u00f1os, ni\u00f1as y el personal puedan disponer de las condiciones que merecen para aprender y ense\u00f1ar\u00bb.<\/p>\n<p>El programa provincial de Infraestructura Escolar tiene como objetivo lograr que las escuelas bonaerenses sean habitables, funcionales y seguras. Por ello, las obras est\u00e1n orientadas a la refacci\u00f3n, ampliaci\u00f3n y construcci\u00f3n edilicia de las instituciones educativas.<\/p>\n<p>Durante la actividad tambi\u00e9n estuvieron presentes la directora de la UGC 7, Victoria Babjaczuk; el vicepresidente del Consejo Escolar, Mat\u00edas Mart\u00ednez; y la directora del establecimiento educativo, Nancy Funes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El intendente Lucas Ghi recorri\u00f3 la Escuela Primaria N\u00ba11 de Villa Sarmiento para supervisar las obras de refacci\u00f3n que se llevan adelante a trav\u00e9s del programa bonaerense Escuelas a la Obra. Las intervenciones constan de la renovaci\u00f3n completa de los ba\u00f1os con trabajos de ventilaci\u00f3n e iluminaci\u00f3n incluidas. Cuentan con una inversi\u00f3n de 2.239.000 de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17862,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,20],"tags":[131,73,144],"class_list":["post-17861","post","type-post","status-publish","format-standard","has-post-thumbnail","category-moron","category-municipios","tag-educacion","tag-lucas-ghi","tag-obras-publicas"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Gu\u00eda de Noticias\"\/>\n\t<meta name=\"keywords\" content=\"educaci\u00f3n,lucas ghi,obras p\u00fablicas,mor\u00f3n,municipios\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/guiadenoticias.com.ar\/diario\/avanzan-las-refacciones-en-escuelas-de-moron\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Gu\u00eda de Noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Avanzan las refacciones en escuelas de Mor\u00f3n |\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/guiadenoticias.com.ar\/diario\/avanzan-las-refacciones-en-escuelas-de-moron\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2021\/06\/obras.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2021\/06\/obras.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t\t<meta property=\"og:image:height\" content=\"598\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-06-28T04:44:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-06-29T04:45:20+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Guia-de-Noticias-1075696352450389\" \/>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Avanzan las refacciones en escuelas de Mor\u00f3n |","description":"","canonical_url":"https:\/\/guiadenoticias.com.ar\/diario\/avanzan-las-refacciones-en-escuelas-de-moron\/","robots":"max-image-preview:large","keywords":"educaci\u00f3n,lucas ghi,obras p\u00fablicas,mor\u00f3n,municipios","webmasterTools":{"miscellaneous":""},"schema":null,"og:locale":"es_ES","og:site_name":"Gu\u00eda de Noticias","og:type":"article","og:title":"Avanzan las refacciones en escuelas de Mor\u00f3n |","og:url":"https:\/\/guiadenoticias.com.ar\/diario\/avanzan-las-refacciones-en-escuelas-de-moron\/","og:image":"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2021\/06\/obras.jpg","og:image:secure_url":"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2021\/06\/obras.jpg","og:image:width":900,"og:image:height":598,"article:published_time":"2021-06-28T04:44:53+00:00","article:modified_time":"2021-06-29T04:45:20+00:00","article:publisher":"https:\/\/www.facebook.com\/Guia-de-Noticias-1075696352450389"},"aioseo_meta_data":{"post_id":"17861","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-06-29 04:41:13","updated":"2025-06-05 06:10:40","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts\/17861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/comments?post=17861"}],"version-history":[{"count":1,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts\/17861\/revisions"}],"predecessor-version":[{"id":17863,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts\/17861\/revisions\/17863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/media\/17862"}],"wp:attachment":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/media?parent=17861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/categories?post=17861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/tags?post=17861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}