{"id":22529,"date":"2024-03-24T23:00:24","date_gmt":"2024-03-25T02:00:24","guid":{"rendered":"https:\/\/guiadenoticias.com.ar\/diario\/?p=22529"},"modified":"2024-04-03T02:09:55","modified_gmt":"2024-04-03T05:09:55","slug":"moron-conmemoro-el-dia-nacional-de-la-memoria","status":"publish","type":"post","link":"https:\/\/guiadenoticias.com.ar\/diario\/moron-conmemoro-el-dia-nacional-de-la-memoria\/","title":{"rendered":"Mor\u00f3n conmemor\u00f3 el D\u00eda Nacional de la Memoria"},"content":{"rendered":"<p>El Municipio de Mor\u00f3n organiz\u00f3 un fin de semana con actividades culturales y musicales por el D\u00eda Nacional de la Memoria por la Verdad y la Justicia, que se conmemora cada 24 de marzo. El s\u00e1bado 23 se llev\u00f3 a cabo una jornada con propuestas culturales que tuvo lugar en el Predio Quinta Ser\u00e9 &#8211; Polideportivo Gorki Grana y convoc\u00f3 a miles de personas.<\/p>\n<p>En ese marco, tambi\u00e9n tuvo lugar el acto central bajo las consignas \u201cMemoria S\u00ed. Pa\u00f1uelos hoy y siempre en todo el pa\u00eds\u201d, encabezado por el intendente Lucas Ghi, el ex intendente de Mor\u00f3n, Mart\u00edn Sabbatella, la diputada M\u00f3nica Macha, junto con representantes de organismos de Derechos Humanos.<\/p>\n<p>Participaron la Asociaci\u00f3n Ser\u00e9 por la Memoria y la Vida, Sobrevivientes Mansi\u00f3n Ser\u00e9, Asociaci\u00f3n ex Detenidos Mansi\u00f3n Ser\u00e9 zona oeste, Asociaci\u00f3n Memoria y Lucha (AMyL), Espacio para la Memoria El Chalet, Espacio de Memoria de los Pueblos Originarios (EMPO), Hijos gran Mor\u00f3n, Liga Argentina por los DDHH filial oeste, el Centro de Veteranos de Malvinas de Mor\u00f3n, Barrios por la Memoria zona oeste, Instituto Hist\u00f3rico Belgraniano de Ituzaing\u00f3, SUTEBA Mor\u00f3n, SUTEBA Ituzaing\u00f3, Familiares de Desaparecidos y V\u00edctimas del Terrorismo de Estado.<\/p>\n<p>Entre las propuestas art\u00edsticas se presentaron Militantes del Climax, Willy Bronca, Orquesta Popular San Bomba, Sir\u00e9 Sir\u00e9, Guillermina, la Sinf\u00f3nica Municipal y Parkour en el Geri\u00e1trico, entre otros. Adem\u00e1s, hubo una charla sobre Fotograf\u00eda y Derechos Humanos con M\u00f3nica Hasenberg y Cora Gamarnik, y se present\u00f3 el libro \u201cLos nietos te cuentan c\u00f3mo fue\u201d, en el que 13 nietos y nietas recuperadas relatan sus vivencias.<\/p>\n<p>Como cierre, el 24 de marzo casi 10 mil personas participaron de la Prueba Atl\u00e9tica por la Memoria, la Verdad y la Justicia que corri\u00f3 por las calles de Castelar. Hubo circuitos de 10K y 5K, tanto a nivel competitivo como participativo.<\/p>\n<p>En el hoy Predio Quinta Ser\u00e9 funcion\u00f3 durante la \u00faltima dictadura c\u00edvico militar un Centro Clandestino de Detenci\u00f3n y Exterminio. En 2000, por decisi\u00f3n del entonces intendente Sabbatella, junto con la Asociaci\u00f3n Ser\u00e9 por la Memoria y la Vida, fue resignificado e inaugurado como Casa de la Memoria y la Vida, sede actual de la Direcci\u00f3n de Derechos Humanos de Mor\u00f3n. En 2015, el predio fue declarado Lugar Hist\u00f3rico Nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Municipio de Mor\u00f3n organiz\u00f3 un fin de semana con actividades culturales y musicales por el D\u00eda Nacional de la Memoria por la Verdad y la Justicia, que se conmemora cada 24 de marzo. El s\u00e1bado 23 se llev\u00f3 a cabo una jornada con propuestas culturales que tuvo lugar en el Predio Quinta Ser\u00e9 &#8211; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22530,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[70,28,20],"tags":[73,93],"class_list":["post-22529","post","type-post","status-publish","format-standard","has-post-thumbnail","category-las-mas-leidas","category-moron","category-municipios","tag-lucas-ghi","tag-martin-sabbatella"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Gu\u00eda de Noticias\"\/>\n\t<meta name=\"keywords\" content=\"lucas ghi,mart\u00edn sabbatella,las m\u00e1s leidas,mor\u00f3n,municipios\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/guiadenoticias.com.ar\/diario\/moron-conmemoro-el-dia-nacional-de-la-memoria\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Gu\u00eda de Noticias\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Mor\u00f3n conmemor\u00f3 el D\u00eda Nacional de la Memoria |\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/guiadenoticias.com.ar\/diario\/moron-conmemoro-el-dia-nacional-de-la-memoria\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2024\/03\/mail.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2024\/03\/mail.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t\t<meta property=\"og:image:height\" content=\"562\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-03-25T02:00:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-04-03T05:09:55+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Guia-de-Noticias-1075696352450389\" \/>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mor\u00f3n conmemor\u00f3 el D\u00eda Nacional de la Memoria |","description":"","canonical_url":"https:\/\/guiadenoticias.com.ar\/diario\/moron-conmemoro-el-dia-nacional-de-la-memoria\/","robots":"max-image-preview:large","keywords":"lucas ghi,mart\u00edn sabbatella,las m\u00e1s leidas,mor\u00f3n,municipios","webmasterTools":{"miscellaneous":""},"schema":null,"og:locale":"es_ES","og:site_name":"Gu\u00eda de Noticias","og:type":"article","og:title":"Mor\u00f3n conmemor\u00f3 el D\u00eda Nacional de la Memoria |","og:url":"https:\/\/guiadenoticias.com.ar\/diario\/moron-conmemoro-el-dia-nacional-de-la-memoria\/","og:image":"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2024\/03\/mail.jpg","og:image:secure_url":"https:\/\/guiadenoticias.com.ar\/diario\/wp-content\/uploads\/2024\/03\/mail.jpg","og:image:width":900,"og:image:height":562,"article:published_time":"2024-03-25T02:00:24+00:00","article:modified_time":"2024-04-03T05:09:55+00:00","article:publisher":"https:\/\/www.facebook.com\/Guia-de-Noticias-1075696352450389"},"aioseo_meta_data":{"post_id":"22529","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-03-29 06:03:44","updated":"2025-06-05 07:58:26","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts\/22529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/comments?post=22529"}],"version-history":[{"count":1,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts\/22529\/revisions"}],"predecessor-version":[{"id":22532,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/posts\/22529\/revisions\/22532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/media\/22530"}],"wp:attachment":[{"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/media?parent=22529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/categories?post=22529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guiadenoticias.com.ar\/diario\/wp-json\/wp\/v2\/tags?post=22529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}